{"id":50114,"date":"2022-06-02T13:28:35","date_gmt":"2022-06-02T13:28:35","guid":{"rendered":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter.jpg"},"modified":"2022-06-02T13:34:16","modified_gmt":"2022-06-02T13:34:16","slug":"ingo-walter-8","status":"inherit","type":"attachment","link":"https:\/\/stronghold-terrain.de\/en\/heerschau-2022-mai-ergebnisse\/ingo-walter-8\/","title":{"rendered":"Ingo Walter"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"class_list":["post-50114","attachment","type-attachment","status-inherit","hentry"],"filename":"Ingo-Walter.jpg","filesize":328842,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"88\" src=\"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-300x88.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-300x88.jpg 300w, https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-1024x301.jpg 1024w, https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-768x225.jpg 768w, https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-1536x451.jpg 1536w, https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-2048x601.jpg 2048w, https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-555x163.jpg 555w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Ingo Walter<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":751,"file":"2022\/06\/Ingo-Walter-scaled.jpg","filesize":328842,"sizes":{"medium":{"file":"Ingo-Walter-300x88.jpg","width":300,"height":88,"filesize":7791,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-300x88.jpg"},"large":{"file":"Ingo-Walter-1024x301.jpg","width":1024,"height":301,"filesize":67108,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-1024x301.jpg"},"thumbnail":{"file":"Ingo-Walter-150x150.jpg","width":150,"height":150,"filesize":7282,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-150x150.jpg"},"medium_large":{"file":"Ingo-Walter-768x225.jpg","width":768,"height":225,"filesize":40394,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-768x225.jpg"},"1536x1536":{"file":"Ingo-Walter-1536x451.jpg","width":1536,"height":451,"filesize":137358,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-1536x451.jpg"},"2048x2048":{"file":"Ingo-Walter-2048x601.jpg","width":2048,"height":601,"filesize":226258,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-2048x601.jpg"},"woocommerce_thumbnail":{"file":"Ingo-Walter-262x328.jpg","width":262,"height":328,"filesize":23185,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-262x328.jpg"},"woocommerce_single":{"file":"Ingo-Walter-555x163.jpg","width":555,"height":163,"filesize":22829,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-555x163.jpg"},"woocommerce_gallery_thumbnail":{"file":"Ingo-Walter-100x100.jpg","width":100,"height":100,"filesize":3886,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-100x100.jpg"},"woosq":{"file":"Ingo-Walter-460x460.jpg","width":460,"height":460,"filesize":51523,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-460x460.jpg"},"full":{"file":"Ingo-Walter-scaled.jpg","width":2560,"height":751,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-scaled.jpg"}},"image_meta":{"aperture":"1.85","credit":"","camera":"M2011K2G","caption":"","created_timestamp":"1653931514","copyright":"","focal_length":"6.83","iso":"248","shutter_speed":"0.01","title":"","orientation":"1","keywords":[]},"original_image":"Ingo-Walter.jpg"},"post":50083,"source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2022\/06\/Ingo-Walter-scaled.jpg","_links":{"self":[{"href":"https:\/\/stronghold-terrain.de\/en\/wp-json\/wp\/v2\/media\/50114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stronghold-terrain.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/stronghold-terrain.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/stronghold-terrain.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/stronghold-terrain.de\/en\/wp-json\/wp\/v2\/comments?post=50114"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":50083,"href":"https:\/\/stronghold-terrain.de\/en\/wp-json\/wp\/v2\/posts\/50083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}