{"id":57446,"date":"2024-01-16T09:12:59","date_gmt":"2024-01-16T09:12:59","guid":{"rendered":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4.jpg"},"modified":"2024-01-16T09:12:59","modified_gmt":"2024-01-16T09:12:59","slug":"szenario-2024-4","status":"inherit","type":"attachment","link":"https:\/\/stronghold-terrain.de\/en\/szenario-2024-impressionen\/szenario-2024-4\/","title":{"rendered":"Szenario 2024 4"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_crdt_document":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"class_list":["post-57446","attachment","type-attachment","status-inherit","hentry"],"filename":"Szenario-2024-4.jpg","filesize":388693,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"226\" src=\"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-300x226.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-300x226.jpg 300w, https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-1024x770.jpg 1024w, https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-768x578.jpg 768w, https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-555x418.jpg 555w, https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":963,"file":"2024\/01\/Szenario-2024-4.jpg","filesize":388693,"sizes":{"medium":{"file":"Szenario-2024-4-300x226.jpg","width":300,"height":226,"filesize":23433,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-300x226.jpg"},"large":{"file":"Szenario-2024-4-1024x770.jpg","width":1024,"height":770,"filesize":203798,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-1024x770.jpg"},"thumbnail":{"file":"Szenario-2024-4-150x150.jpg","width":150,"height":150,"filesize":8846,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-150x150.jpg"},"medium_large":{"file":"Szenario-2024-4-768x578.jpg","width":768,"height":578,"filesize":131874,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-768x578.jpg"},"woocommerce_thumbnail":{"file":"Szenario-2024-4-262x328.jpg","width":262,"height":328,"filesize":28770,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-262x328.jpg"},"woocommerce_single":{"file":"Szenario-2024-4-555x418.jpg","width":555,"height":418,"filesize":72431,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-555x418.jpg"},"woocommerce_gallery_thumbnail":{"file":"Szenario-2024-4-100x100.jpg","width":100,"height":100,"filesize":4526,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-100x100.jpg"},"woosq":{"file":"Szenario-2024-4-460x460.jpg","width":460,"height":460,"filesize":67165,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4-460x460.jpg"},"full":{"file":"Szenario-2024-4.jpg","width":1280,"height":963,"mime_type":"image\/jpeg","source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4.jpg"}},"image_meta":{"aperture":"1.85","credit":"","camera":"Pixel 6","caption":"","created_timestamp":"1705157906","copyright":"","focal_length":"6.81","iso":"320","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]}},"post":57442,"source_url":"https:\/\/stronghold-terrain.de\/wp-content\/uploads\/2024\/01\/Szenario-2024-4.jpg","_links":{"self":[{"href":"https:\/\/stronghold-terrain.de\/en\/wp-json\/wp\/v2\/media\/57446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stronghold-terrain.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/stronghold-terrain.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/stronghold-terrain.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/stronghold-terrain.de\/en\/wp-json\/wp\/v2\/comments?post=57446"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":57442,"href":"https:\/\/stronghold-terrain.de\/en\/wp-json\/wp\/v2\/posts\/57442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}